{"id":6558,"date":"2025-04-25T09:44:10","date_gmt":"2025-04-25T00:44:10","guid":{"rendered":"https:\/\/edu2.city.yurihonjo.lg.jp\/nishime-es\/?p=6558"},"modified":"2025-12-05T09:15:30","modified_gmt":"2025-12-05T00:15:30","slug":"post-6558","status":"publish","type":"post","link":"https:\/\/edu2.city.yurihonjo.lg.jp\/nishime-es\/post-6558\/","title":{"rendered":"\u4ee4\u548c7\u5e74\u5ea6 \u5b66\u6821\u4fbf\u308a\u300c\u77e5\u80fd\u5553\u767a\u300dNo.\uff13"},"content":{"rendered":"\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/edu2.city.yurihonjo.lg.jp\/nishime-es\/wp-content\/uploads\/sites\/13\/2025\/04\/7411eff97e9f9e27452e173892061587.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"\u2116\uff13\u5150\u7ae5\u4f1a\u8a8d\u8a3c\u5f0f\u306e\u57cb\u3081\u8fbc\u307f\u3002\"><\/object><a id=\"wp-block-file--media-55c9a116-b962-4377-9945-ce2898be33aa\" href=\"https:\/\/edu2.city.yurihonjo.lg.jp\/nishime-es\/wp-content\/uploads\/sites\/13\/2025\/04\/7411eff97e9f9e27452e173892061587.pdf\">\u2116\uff13\u5150\u7ae5\u4f1a\u8a8d\u8a3c\u5f0f<\/a><a href=\"https:\/\/edu2.city.yurihonjo.lg.jp\/nishime-es\/wp-content\/uploads\/sites\/13\/2025\/04\/7411eff97e9f9e27452e173892061587.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-55c9a116-b962-4377-9945-ce2898be33aa\">\u30c0\u30a6\u30f3\u30ed\u30fc\u30c9<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":29,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6558","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/edu2.city.yurihonjo.lg.jp\/nishime-es\/wp-json\/wp\/v2\/posts\/6558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edu2.city.yurihonjo.lg.jp\/nishime-es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/edu2.city.yurihonjo.lg.jp\/nishime-es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/edu2.city.yurihonjo.lg.jp\/nishime-es\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/edu2.city.yurihonjo.lg.jp\/nishime-es\/wp-json\/wp\/v2\/comments?post=6558"}],"version-history":[{"count":1,"href":"https:\/\/edu2.city.yurihonjo.lg.jp\/nishime-es\/wp-json\/wp\/v2\/posts\/6558\/revisions"}],"predecessor-version":[{"id":6563,"href":"https:\/\/edu2.city.yurihonjo.lg.jp\/nishime-es\/wp-json\/wp\/v2\/posts\/6558\/revisions\/6563"}],"wp:attachment":[{"href":"https:\/\/edu2.city.yurihonjo.lg.jp\/nishime-es\/wp-json\/wp\/v2\/media?parent=6558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/edu2.city.yurihonjo.lg.jp\/nishime-es\/wp-json\/wp\/v2\/categories?post=6558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/edu2.city.yurihonjo.lg.jp\/nishime-es\/wp-json\/wp\/v2\/tags?post=6558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}